{"id":1512,"date":"2022-07-15T14:53:54","date_gmt":"2022-07-15T12:53:54","guid":{"rendered":"https:\/\/auslaenderbehoerde.org\/?page_id=1512"},"modified":"2022-07-15T14:53:54","modified_gmt":"2022-07-15T12:53:54","slug":"auslaenderbehoerde-nordhausen","status":"publish","type":"page","link":"https:\/\/auslaenderbehoerde.org\/nl\/immigratiedienst-nordhausen\/","title":{"rendered":"immigratiebureau Nordhausen"},"content":{"rendered":"<p>Hier vindt u de verschillende contactmogelijkheden en andere nuttige informatie voor het immigratiebureau Nordhausen - Th\u00fcringen<\/p>\n<p><strong>Adres:<\/strong> Districtskantoor van het district Nordhausen, Behringstra\u00dfe 3, 99734 Nordhausen<br \/>\n<strong>Telefoon:<\/strong> (03631) 911356<br \/>\n<strong>Fax:<\/strong> (03631) 911104<br \/>\n<strong>Website:<\/strong> <a href=\"https:\/\/landkreis-nordhausen.de\/\">www.landratsamt-nordhausen.de<\/a><br \/>\n<strong>Openingstijden:<\/strong> zie website<\/p>\n<p><iframe style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2483.3439191986768!2d10.784355551332537!3d51.5069061184604!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x47a4ffea54cfc9a3%3A0x367944a696a859f9!2sBehringstra%C3%9Fe%203%2C%2099734%20Nordhausen!5e0!3m2!1sde!2sde!4v1657889626355!5m2!1sde!2sde\" width=\"600\" height=\"450\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>Taken van het immigratiebureau van Nordhausen<\/h2>\n<p>Het immigratiebureau in Nordhausen is verantwoordelijk voor de inwoners van Nordhausen en de bijbehorende steden. De autoriteit is het eerste adres voor buitenlanders die uit het buitenland komen. Het is verantwoordelijk voor het afgeven of weigeren van verblijfsvergunningen volgens de respectieve verblijfsdoelen van de verblijfswet.<\/p>\n<p>De Dienst Vreemdelingenzaken is ook verantwoordelijk voor de afgifte van de <a href=\"https:\/\/auslaenderbehoerde.org\/nl\/verblijfsvergunning\/\">verblijfsvergunning<\/a>, <a href=\"https:\/\/auslaenderbehoerde.org\/nl\/verbintenisverklaring\/\">verbintenisverklaring<\/a>, reisdocumenten en gedoogvergunningen voor buitenlanders. De immigratiedienst is ermee bezig <a href=\"https:\/\/www.gesetze-im-internet.de\/aufenthg_2004\/__71.html\" target=\"_blank\" rel=\"noopener external noreferrer\" data-wpel-link=\"external\">Sectie 71<\/a> AufenthG en is verantwoordelijk voor het reguleren van alle beslissingen en maatregelen die van invloed zijn op het paspoort en de verblijfsrechten van buitenlanders.<\/p>\n<p>De verantwoordelijkheid van de vreemdelingenautoriteit strekt zich ook uit tot tal van andere taken. Het type en de duur van de verblijfsvergunning lopen sterk uiteen. Sommigen krijgen een termijn, anderen krijgen geen verblijfsvergunning en krijgen een uitreisvergunning op grond van de Verblijfswet.<\/p>\n<p>De immigratiediensten zijn ook verantwoordelijk voor asielzoekers en ontheemden. Jij beslist over <a href=\"https:\/\/auslaenderbehoerde.org\/nl\/verblijfsvergunning-2\/\">verblijfsvergunning<\/a> en deze afgeven als de beslissing positief is.<\/p>\n<p><strong>Hier is een overzicht van waar de immigratie-autoriteiten verantwoordelijk voor zijn:<\/strong><\/p>\n<ul style=\"list-style-type: circle;\">\n<li>vluchtelingenhulp<\/li>\n<li>sociale zekerheid<\/li>\n<li>inburgeringscursussen<\/li>\n<li>Organisatie en goedkeuring van binnenkomst en verblijf in Duitsland<\/li>\n<li>recht op een uitkering<\/li>\n<li>vergoeding en gezondheidszorg<\/li>\n<li>burgerlijke staat<\/li>\n<li>verbintenisverklaring<\/li>\n<li>accommodatie opties<\/li>\n<li>register<\/li>\n<li>asielprocedure<\/li>\n<\/ul>\n<h3>Hoe kan ik een afspraak maken met de Dienst Vreemdelingenzaken? <span id=\"Wie_kann_ich_einen_Termin_beim_Jugendamt_vereinbaren\">mee eens zijn?<\/span><\/h3>\n<p>Er zijn verschillende manieren om een afspraak te maken bij de Dienst Vreemdelingenzaken. De kantoren zijn meestal persoonlijk, telefonisch, per e-mail of online te bereiken. Het adres en de openingstijden zijn online in te zien. In sommige steden kunt u een afspraak maken via het stadsserviceportaal en online formulieren downloaden. Zorg ervoor dat u alle benodigde documenten hebt ingevuld voordat u het bureau bezoekt.<\/p>\n<div class=\"su-note\"  style=\"border-color:#d1d1d0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#ebebea;border-color:#ffffff;color:#444444;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><b>Een mededeling: <\/b>Voor kantoren en autoriteiten heeft u de documenten of certificaten meestal nodig als: <a href=\"https:\/\/tidd.ly\/3y8DKdr\" target=\"_blank\" rel=\"noopener\">be\u00ebdigde vertaling<\/a>*.<\/div><\/div>\n<p><strong>Verwacht u bezoekers uit het buitenland?<\/strong> Met een <a href=\"https:\/\/auslaenderbehoerde.org\/nl\/reisverzekering-voor-buitenlandse-gasten\/\">Reisverzekering voor buitenlandse gasten<\/a> profiteren van uitgebreide bescherming in Duitsland en Europa.<\/p>\n<h3>Verdere immigratiediensten en informatie<\/h3>\n<ul style=\"list-style-type: circle;\">\n<li><a href=\"https:\/\/auslaenderbehoerde.org\/nl\/immigratiediensten-in-thueringen\/\">immigratiediensten in Th\u00fcringen<\/a><\/li>\n<li><a href=\"https:\/\/auslaenderbehoerde.org\/nl\/\">Immigratie-autoriteiten in Duitsland<\/a><\/li>\n<li><a href=\"https:\/\/auslaenderbehoerde.org\/nl\/eerste-stappen-in-duitsland\/\" data-wpel-link=\"internal\">Eerste stappen in Duitsland<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Hier vindt u de verschillende contactmogelijkheden en andere nuttige informatie voor de immigratiedienst Nordhausen - Th\u00fcringen Adres: Districtskantoor Nordhausen, Behringstra\u00dfe 3, 99734 Nordhausen Telefoon: (03631) 911356 Fax: (03631) 911104 Website: www.landratsamt-nordhausen. de Openingstijden: zie website Taken van de vreemdelingendienst van Nordhausen De vreemdelingendienst van Nordhausen is verantwoordelijk voor de inwoners van Nordhausen en de aangesloten steden. De Autoriteit\u2026&nbsp;<a href=\"https:\/\/auslaenderbehoerde.org\/nl\/immigratiedienst-nordhausen\/\" rel=\"bookmark\">Lees verder \u00bb<span class=\"screen-reader-text\">immigratiebureau Nordhausen<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":65,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","footnotes":""},"class_list":["post-1512","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ausl\u00e4nderbeh\u00f6rde Nordhausen | Adresse und Kontaktdaten<\/title>\n<meta name=\"description\" content=\"Ausl\u00e4nderbeh\u00f6rde Nordhausen | Hier finden Sie alle Informationen wie Adresse und Anschrift \u2713 Telefonnummer, Kontakt und \u00d6ffnungszeiten\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auslaenderbehoerde.org\/nl\/immigratiedienst-nordhausen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ausl\u00e4nderbeh\u00f6rde Nordhausen | Adresse und Kontaktdaten\" \/>\n<meta property=\"og:description\" content=\"Ausl\u00e4nderbeh\u00f6rde Nordhausen | Hier finden Sie alle Informationen wie Adresse und Anschrift \u2713 Telefonnummer, Kontakt und \u00d6ffnungszeiten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auslaenderbehoerde.org\/nl\/immigratiedienst-nordhausen\/\" \/>\n<meta property=\"og:site_name\" content=\"auslaenderbehoerde.org\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auslaenderbehoerde.org\/wp-content\/uploads\/2022\/06\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/\",\"url\":\"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/\",\"name\":\"Ausl\u00e4nderbeh\u00f6rde Nordhausen | Adresse und Kontaktdaten\",\"isPartOf\":{\"@id\":\"https:\/\/auslaenderbehoerde.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/auslaenderbehoerde.org\/wp-content\/uploads\/2022\/06\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg\",\"datePublished\":\"2022-07-15T12:53:54+00:00\",\"description\":\"Ausl\u00e4nderbeh\u00f6rde Nordhausen | Hier finden Sie alle Informationen wie Adresse und Anschrift \u2713 Telefonnummer, Kontakt und \u00d6ffnungszeiten\",\"breadcrumb\":{\"@id\":\"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/#primaryimage\",\"url\":\"https:\/\/auslaenderbehoerde.org\/wp-content\/uploads\/2022\/06\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg\",\"contentUrl\":\"https:\/\/auslaenderbehoerde.org\/wp-content\/uploads\/2022\/06\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg\",\"width\":900,\"height\":675,\"caption\":\"Ausl\u00e4nderbeh\u00f6rde\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/auslaenderbehoerde.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ausl\u00e4nderbeh\u00f6rde Nordhausen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/auslaenderbehoerde.org\/#website\",\"url\":\"https:\/\/auslaenderbehoerde.org\/\",\"name\":\"auslaenderbehoerde.org\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/auslaenderbehoerde.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Immigratiebureau Nordhausen | adres en contactgegevens","description":"Immigratiebureau Nordhausen | Hier vindt u alle informatie zoals adres en adres \u2713 telefoonnummer, contact en openingstijden","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auslaenderbehoerde.org\/nl\/immigratiedienst-nordhausen\/","og_locale":"nl_NL","og_type":"article","og_title":"Ausl\u00e4nderbeh\u00f6rde Nordhausen | Adresse und Kontaktdaten","og_description":"Ausl\u00e4nderbeh\u00f6rde Nordhausen | Hier finden Sie alle Informationen wie Adresse und Anschrift \u2713 Telefonnummer, Kontakt und \u00d6ffnungszeiten","og_url":"https:\/\/auslaenderbehoerde.org\/nl\/immigratiedienst-nordhausen\/","og_site_name":"auslaenderbehoerde.org","og_image":[{"width":900,"height":675,"url":"https:\/\/auslaenderbehoerde.org\/wp-content\/uploads\/2022\/06\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/","url":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/","name":"Immigratiebureau Nordhausen | adres en contactgegevens","isPartOf":{"@id":"https:\/\/auslaenderbehoerde.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/#primaryimage"},"image":{"@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/#primaryimage"},"thumbnailUrl":"https:\/\/auslaenderbehoerde.org\/wp-content\/uploads\/2022\/06\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg","datePublished":"2022-07-15T12:53:54+00:00","description":"Immigratiebureau Nordhausen | Hier vindt u alle informatie zoals adres en adres \u2713 telefoonnummer, contact en openingstijden","breadcrumb":{"@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/#primaryimage","url":"https:\/\/auslaenderbehoerde.org\/wp-content\/uploads\/2022\/06\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg","contentUrl":"https:\/\/auslaenderbehoerde.org\/wp-content\/uploads\/2022\/06\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg","width":900,"height":675,"caption":"Ausl\u00e4nderbeh\u00f6rde"},{"@type":"BreadcrumbList","@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-nordhausen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/auslaenderbehoerde.org\/"},{"@type":"ListItem","position":2,"name":"Ausl\u00e4nderbeh\u00f6rde Nordhausen"}]},{"@type":"WebSite","@id":"https:\/\/auslaenderbehoerde.org\/#website","url":"https:\/\/auslaenderbehoerde.org\/","name":"auslaenderbehoerde.org","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auslaenderbehoerde.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/pages\/1512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/comments?post=1512"}],"version-history":[{"count":1,"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/pages\/1512\/revisions"}],"predecessor-version":[{"id":1513,"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/pages\/1512\/revisions\/1513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/media\/65"}],"wp:attachment":[{"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/media?parent=1512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}