{"id":424,"date":"2022-07-05T16:14:56","date_gmt":"2022-07-05T14:14:56","guid":{"rendered":"https:\/\/auslaenderbehoerde.org\/?page_id=424"},"modified":"2022-07-05T16:14:56","modified_gmt":"2022-07-05T14:14:56","slug":"auslaenderbehoerde-schwaebisch-hall","status":"publish","type":"page","link":"https:\/\/auslaenderbehoerde.org\/nl\/immigratie-autoriteit-schwaebisch-hall\/","title":{"rendered":"Immigratiebureau Schw\u00e4bisch Hall"},"content":{"rendered":"<p>Hier vindt u de verschillende contactmogelijkheden en andere nuttige informatie voor de immigratiedienst Schw\u00e4bisch Hall \u2013 Baden-W\u00fcrttemberg.<\/p>\n<p><strong>Adres:<\/strong> Immigratiebureau Schw\u00e4bisch Hall, Gymnasiumstrasse 2, 74523 Schw\u00e4bisch Hall<br \/>\n<strong>Telefoon:<\/strong> 0791 751480<br \/>\n<strong>Fax:<\/strong> 0791 751409<br \/>\n<strong>Website:<\/strong> <a href=\"https:\/\/www.schwaebischhall.de\/de\/startseite\">www.schwaebischhall.de<\/a><br \/>\n<strong>Openingstijden:<\/strong> zie website<\/p>\n<p><iframe style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2611.6151781669532!2d9.736449551503393!3d49.11295067921173!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x479850749544cb73%3A0x95319ff331042ed9!2sGymnasiumstra%C3%9Fe%202%2C%2074523%20Schw%C3%A4bisch%20Hall!5e0!3m2!1sde!2sde!4v1657030487150!5m2!1sde!2sde\" width=\"600\" height=\"450\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>Taken van het immigratiebureau Schw\u00e4bisch Hall<\/h2>\n<p>Het immigratiebureau van Schw\u00e4bisch Hall is verantwoordelijk voor de inwoners van Schw\u00e4bisch Hall en de bijbehorende steden. De autoriteit is het eerste adres voor buitenlanders die uit het buitenland komen. Het is verantwoordelijk voor het afgeven of weigeren van verblijfsvergunningen volgens de respectieve verblijfsdoelen van de verblijfswet.<\/p>\n<p>De Dienst Vreemdelingenzaken is ook verantwoordelijk voor de afgifte van de <a href=\"https:\/\/auslaenderbehoerde.org\/nl\/verblijfsvergunning\/\">verblijfsvergunning<\/a>, <a href=\"https:\/\/auslaenderbehoerde.org\/nl\/verbintenisverklaring\/\">verbintenisverklaring<\/a>, reisdocumenten en gedoogvergunningen voor buitenlanders. De immigratiedienst is ermee bezig <a href=\"https:\/\/www.gesetze-im-internet.de\/aufenthg_2004\/__71.html\" target=\"_blank\" rel=\"noopener external noreferrer\" data-wpel-link=\"external\">Sectie 71<\/a> AufenthG en is verantwoordelijk voor het reguleren van alle beslissingen en maatregelen die van invloed zijn op het paspoort en de verblijfsrechten van buitenlanders.<\/p>\n<p>De verantwoordelijkheid van de vreemdelingenautoriteit strekt zich ook uit tot tal van andere taken. Het type en de duur van de verblijfsvergunning lopen sterk uiteen. Sommigen krijgen een termijn, anderen krijgen geen verblijfsvergunning en krijgen een uitreisvergunning op grond van de Verblijfswet.<\/p>\n<p>De immigratiediensten zijn ook verantwoordelijk voor asielzoekers en ontheemden. Jij beslist over <a href=\"https:\/\/auslaenderbehoerde.org\/nl\/verblijfsvergunning-2\/\">verblijfsvergunning<\/a> en deze afgeven als de beslissing positief is.<\/p>\n<p><strong>Hier is een overzicht van waar de immigratie-autoriteiten verantwoordelijk voor zijn:<\/strong><\/p>\n<ul style=\"list-style-type: circle;\">\n<li>vluchtelingenhulp<\/li>\n<li>sociale zekerheid<\/li>\n<li>inburgeringscursussen<\/li>\n<li>Organisatie en goedkeuring van binnenkomst en verblijf in Duitsland<\/li>\n<li>recht op een uitkering<\/li>\n<li>vergoeding en gezondheidszorg<\/li>\n<li>burgerlijke staat<\/li>\n<li>verbintenisverklaring<\/li>\n<li>accommodatie opties<\/li>\n<li>register<\/li>\n<li>asielprocedure<\/li>\n<\/ul>\n<h3>Hoe kan ik een afspraak maken met de Dienst Vreemdelingenzaken? <span id=\"Wie_kann_ich_einen_Termin_beim_Jugendamt_vereinbaren\">mee eens zijn?<\/span><\/h3>\n<p>Er zijn verschillende manieren om een afspraak te maken bij de Dienst Vreemdelingenzaken. De kantoren zijn meestal persoonlijk, telefonisch, per e-mail of online te bereiken. Het adres en de openingstijden zijn online in te zien. In sommige steden kunt u een afspraak maken via het stadsserviceportaal en online formulieren downloaden. Zorg ervoor dat u alle benodigde documenten hebt ingevuld voordat u het bureau bezoekt.<\/p>\n<div class=\"su-note\"  style=\"border-color:#d1d1d0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#ebebea;border-color:#ffffff;color:#444444;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><b>Een mededeling: <\/b>Voor kantoren en autoriteiten heeft u de documenten of certificaten meestal nodig als: <a href=\"https:\/\/tidd.ly\/3y8DKdr\" target=\"_blank\" rel=\"noopener\">be\u00ebdigde vertaling<\/a>*.<\/div><\/div>\n<p><strong>Verwacht u bezoekers uit het buitenland?<\/strong> Met een <a href=\"https:\/\/auslaenderbehoerde.org\/nl\/reisverzekering-voor-buitenlandse-gasten\/\">Reisverzekering voor buitenlandse gasten<\/a> profiteren van uitgebreide bescherming in Duitsland en Europa.<\/p>\n<h3>Verdere immigratiediensten en informatie<\/h3>\n<ul style=\"list-style-type: circle;\">\n<li><a href=\"https:\/\/auslaenderbehoerde.org\/nl\/immigratiediensten-in-baden-wuerttemberg\/\">Immigratie-autoriteiten in Baden-W\u00fcrttemberg<\/a><\/li>\n<li><a href=\"https:\/\/auslaenderbehoerde.org\/nl\/\">Immigratie-autoriteiten in Duitsland<\/a><\/li>\n<li><a href=\"https:\/\/auslaenderbehoerde.org\/nl\/eerste-stappen-in-duitsland\/\" data-wpel-link=\"internal\">Eerste stappen in Duitsland<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Hier vindt u de verschillende contactmogelijkheden en andere nuttige informatie voor het immigratiebureau in Schw\u00e4bisch Hall, Baden-W\u00fcrttemberg. Adres: Immigratiebureau Schw\u00e4bisch Hall, Gymnasiumstra\u00dfe 2, 74523 Schw\u00e4bisch Hall. Telefoon: +49 791 751480. Fax: +49 791 751409. Website: www.schwaebischhall.de. Openingstijden: zie website. Verantwoordelijkheden van het immigratiebureau Schw\u00e4bisch Hall: Het immigratiebureau Schw\u00e4bisch Hall is verantwoordelijk voor de bewoners van Schw\u00e4bisch Hall en\u2026&nbsp;<a href=\"https:\/\/auslaenderbehoerde.org\/nl\/immigratie-autoriteit-schwaebisch-hall\/\" rel=\"bookmark\">Lees verder \u00bb<span class=\"screen-reader-text\">Immigratiebureau Schw\u00e4bisch Hall<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","footnotes":""},"class_list":["post-424","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ausl\u00e4nderbeh\u00f6rde Schw\u00e4bisch Hall | Adresse und Kontaktdaten<\/title>\n<meta name=\"description\" content=\"Ausl\u00e4nderbeh\u00f6rde Schw\u00e4bisch Hall | Hier finden Sie alle Informationen wie Adresse und Anschrift \u2713 Telefonnummer, Kontakt und \u00d6ffnungszeiten\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auslaenderbehoerde.org\/nl\/immigratie-autoriteit-schwaebisch-hall\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ausl\u00e4nderbeh\u00f6rde Schw\u00e4bisch Hall | Adresse und Kontaktdaten\" \/>\n<meta property=\"og:description\" content=\"Ausl\u00e4nderbeh\u00f6rde Schw\u00e4bisch Hall | Hier finden Sie alle Informationen wie Adresse und Anschrift \u2713 Telefonnummer, Kontakt und \u00d6ffnungszeiten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auslaenderbehoerde.org\/nl\/immigratie-autoriteit-schwaebisch-hall\/\" \/>\n<meta property=\"og:site_name\" content=\"auslaenderbehoerde.org\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-schwaebisch-hall\/\",\"url\":\"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-schwaebisch-hall\/\",\"name\":\"Ausl\u00e4nderbeh\u00f6rde Schw\u00e4bisch Hall | Adresse und Kontaktdaten\",\"isPartOf\":{\"@id\":\"https:\/\/auslaenderbehoerde.org\/#website\"},\"datePublished\":\"2022-07-05T14:14:56+00:00\",\"description\":\"Ausl\u00e4nderbeh\u00f6rde Schw\u00e4bisch Hall | Hier finden Sie alle Informationen wie Adresse und Anschrift \u2713 Telefonnummer, Kontakt und \u00d6ffnungszeiten\",\"breadcrumb\":{\"@id\":\"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-schwaebisch-hall\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-schwaebisch-hall\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-schwaebisch-hall\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/auslaenderbehoerde.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ausl\u00e4nderbeh\u00f6rde Schw\u00e4bisch Hall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/auslaenderbehoerde.org\/#website\",\"url\":\"https:\/\/auslaenderbehoerde.org\/\",\"name\":\"auslaenderbehoerde.org\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/auslaenderbehoerde.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Immigratiebureau Schw\u00e4bisch Hall | adres en contactgegevens","description":"Immigratiebureau Schw\u00e4bisch Hall | Hier vindt u alle informatie zoals adres en adres \u2713 telefoonnummer, contact en openingstijden","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auslaenderbehoerde.org\/nl\/immigratie-autoriteit-schwaebisch-hall\/","og_locale":"nl_NL","og_type":"article","og_title":"Ausl\u00e4nderbeh\u00f6rde Schw\u00e4bisch Hall | Adresse und Kontaktdaten","og_description":"Ausl\u00e4nderbeh\u00f6rde Schw\u00e4bisch Hall | Hier finden Sie alle Informationen wie Adresse und Anschrift \u2713 Telefonnummer, Kontakt und \u00d6ffnungszeiten","og_url":"https:\/\/auslaenderbehoerde.org\/nl\/immigratie-autoriteit-schwaebisch-hall\/","og_site_name":"auslaenderbehoerde.org","twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-schwaebisch-hall\/","url":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-schwaebisch-hall\/","name":"Immigratiebureau Schw\u00e4bisch Hall | adres en contactgegevens","isPartOf":{"@id":"https:\/\/auslaenderbehoerde.org\/#website"},"datePublished":"2022-07-05T14:14:56+00:00","description":"Immigratiebureau Schw\u00e4bisch Hall | Hier vindt u alle informatie zoals adres en adres \u2713 telefoonnummer, contact en openingstijden","breadcrumb":{"@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-schwaebisch-hall\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-schwaebisch-hall\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-schwaebisch-hall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/auslaenderbehoerde.org\/"},{"@type":"ListItem","position":2,"name":"Ausl\u00e4nderbeh\u00f6rde Schw\u00e4bisch Hall"}]},{"@type":"WebSite","@id":"https:\/\/auslaenderbehoerde.org\/#website","url":"https:\/\/auslaenderbehoerde.org\/","name":"auslaenderbehoerde.org","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auslaenderbehoerde.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/pages\/424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/comments?post=424"}],"version-history":[{"count":1,"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/pages\/424\/revisions"}],"predecessor-version":[{"id":425,"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/pages\/424\/revisions\/425"}],"wp:attachment":[{"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/media?parent=424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}