{"id":914,"date":"2022-07-11T11:49:26","date_gmt":"2022-07-11T09:49:26","guid":{"rendered":"https:\/\/auslaenderbehoerde.org\/?page_id=914"},"modified":"2022-07-11T11:49:26","modified_gmt":"2022-07-11T09:49:26","slug":"auslaenderbehoerde-luckenwalde","status":"publish","type":"page","link":"https:\/\/auslaenderbehoerde.org\/nl\/immigratiedienst-luckenwalde\/","title":{"rendered":"Immigratiedienst Luckenwalde"},"content":{"rendered":"<p>Hier vindt u de verschillende contactmogelijkheden en andere nuttige informatie voor het immigratiekantoor Luckenwalde - Brandenburg<\/p>\n<p><strong>Adres:<\/strong> District Teltow-Fl\u00e4ming, Am Nuthefliesss 2, 14943 Luckenwalde<br \/>\n<strong>Telefoon:<\/strong> 03371 608 \u2013 2132<br \/>\n<strong>Fax:<\/strong> 03371 608 \u2013 9030<br \/>\n<strong>E-mailadres:<\/strong> <a href=\"mailto:auslaenderbehoerde@teltow-flaeming.de\">auslaenderbehoerde@teltow-flaeming.de<\/a><br \/>\n<strong>Website:<\/strong> <a href=\"https:\/\/www.teltow-flaeming.de\/\">www.teltow-flaeming.de<\/a><br \/>\n<strong>Openingstijden:<\/strong> zie website<\/p>\n<p><iframe style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2451.6583888331006!2d13.167445151596757!3d52.085948279634906!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x47a87a668ab82def%3A0x88a07422d12992c5!2sAm%20Nutheflie%C3%9F%202%2C%2014943%20Luckenwalde!5e0!3m2!1sde!2sde!4v1657532958411!5m2!1sde!2sde\" width=\"600\" height=\"450\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>Taken van de vreemdelingenautoriteit in Luckenwalde<\/h2>\n<p>Het immigratiebureau in Luckenwalde is verantwoordelijk voor de inwoners van Luckenwalde en de aangesloten steden. De autoriteit is het eerste adres voor buitenlanders die uit het buitenland komen. Het is verantwoordelijk voor het afgeven of weigeren van verblijfsvergunningen volgens de respectieve verblijfsdoelen van de verblijfswet.<\/p>\n<p>De Dienst Vreemdelingenzaken is ook verantwoordelijk voor de afgifte van de <a href=\"https:\/\/auslaenderbehoerde.org\/nl\/verblijfsvergunning\/\">verblijfsvergunning<\/a>, <a href=\"https:\/\/auslaenderbehoerde.org\/nl\/verbintenisverklaring\/\">verbintenisverklaring<\/a>, reisdocumenten en gedoogvergunningen voor buitenlanders. De immigratiedienst is ermee bezig <a href=\"https:\/\/www.gesetze-im-internet.de\/aufenthg_2004\/__71.html\" target=\"_blank\" rel=\"noopener external noreferrer\" data-wpel-link=\"external\">Sectie 71<\/a> AufenthG en is verantwoordelijk voor het reguleren van alle beslissingen en maatregelen die van invloed zijn op het paspoort en de verblijfsrechten van buitenlanders.<\/p>\n<p>De verantwoordelijkheid van de vreemdelingenautoriteit strekt zich ook uit tot tal van andere taken. Het type en de duur van de verblijfsvergunning lopen sterk uiteen. Sommigen krijgen een termijn, anderen krijgen geen verblijfsvergunning en krijgen een uitreisvergunning op grond van de Verblijfswet.<\/p>\n<p>De immigratiediensten zijn ook verantwoordelijk voor asielzoekers en ontheemden. Jij beslist over <a href=\"https:\/\/auslaenderbehoerde.org\/nl\/verblijfsvergunning-2\/\">verblijfsvergunning<\/a> en deze afgeven als de beslissing positief is.<\/p>\n<p><strong>Hier is een overzicht van waar de immigratie-autoriteiten verantwoordelijk voor zijn:<\/strong><\/p>\n<ul style=\"list-style-type: circle;\">\n<li>vluchtelingenhulp<\/li>\n<li>sociale zekerheid<\/li>\n<li>inburgeringscursussen<\/li>\n<li>Organisatie en goedkeuring van binnenkomst en verblijf in Duitsland<\/li>\n<li>recht op een uitkering<\/li>\n<li>vergoeding en gezondheidszorg<\/li>\n<li>burgerlijke staat<\/li>\n<li>verbintenisverklaring<\/li>\n<li>accommodatie opties<\/li>\n<li>register<\/li>\n<li>asielprocedure<\/li>\n<\/ul>\n<h3>Hoe kan ik een afspraak maken met de Dienst Vreemdelingenzaken? <span id=\"Wie_kann_ich_einen_Termin_beim_Jugendamt_vereinbaren\">mee eens zijn?<\/span><\/h3>\n<p>Er zijn verschillende manieren om een afspraak te maken bij de Dienst Vreemdelingenzaken. De kantoren zijn meestal persoonlijk, telefonisch, per e-mail of online te bereiken. Het adres en de openingstijden zijn online in te zien. In sommige steden kunt u een afspraak maken via het stadsserviceportaal en online formulieren downloaden. Zorg ervoor dat u alle benodigde documenten hebt ingevuld voordat u het bureau bezoekt.<\/p>\n<div class=\"su-note\"  style=\"border-color:#d1d1d0;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#ebebea;border-color:#ffffff;color:#444444;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><b>Een mededeling: <\/b>Voor kantoren en autoriteiten heeft u de documenten of certificaten meestal nodig als: <a href=\"https:\/\/tidd.ly\/3y8DKdr\" target=\"_blank\" rel=\"noopener\">be\u00ebdigde vertaling<\/a>*.<\/div><\/div>\n<p><strong>Verwacht u bezoekers uit het buitenland?<\/strong> Met een <a href=\"https:\/\/auslaenderbehoerde.org\/nl\/reisverzekering-voor-buitenlandse-gasten\/\">Reisverzekering voor buitenlandse gasten<\/a> profiteren van uitgebreide bescherming in Duitsland en Europa.<\/p>\n<h3>Verdere immigratiediensten en informatie<\/h3>\n<ul style=\"list-style-type: circle;\">\n<li><a href=\"https:\/\/auslaenderbehoerde.org\/nl\/immigratiedienst-in-brandenburg\/\">Immigratie-autoriteiten in Brandenburg<\/a><\/li>\n<li><a href=\"https:\/\/auslaenderbehoerde.org\/nl\/\">Immigratie-autoriteiten in Duitsland<\/a><\/li>\n<li><a href=\"https:\/\/auslaenderbehoerde.org\/nl\/eerste-stappen-in-duitsland\/\" data-wpel-link=\"internal\">Eerste stappen in Duitsland<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Hier vindt u de verschillende contactmogelijkheden en verdere nuttige informatie voor het immigratiekantoor Luckenwalde - Brandenburg Adres: district Teltow-Fl\u00e4ming, Am Nutheflie\u00df 2, 14943 Luckenwalde Telefoon: 03371 608 - 2132 Fax: 03371 608 - 9030 E-mail: auslaenderbehoerde@ teltow-flaeming .de Website: www.teltow-flaeming.de Openingstijden: zie website Taken van de Vreemdelingenautoriteit Luckenwalde De Vreemdelingenautoriteit Luckenwalde is verantwoordelijk voor de inwoners van Luckenwalde...&nbsp;<a href=\"https:\/\/auslaenderbehoerde.org\/nl\/immigratiedienst-luckenwalde\/\" rel=\"bookmark\">Lees verder \u00bb<span class=\"screen-reader-text\">Immigratiedienst Luckenwalde<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":65,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","footnotes":""},"class_list":["post-914","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ausl\u00e4nderbeh\u00f6rde Luckenwalde | Adresse und Kontaktdaten<\/title>\n<meta name=\"description\" content=\"Ausl\u00e4nderbeh\u00f6rde Luckenwalde | Hier finden Sie alle Informationen wie Adresse und Anschrift \u2713 Telefonnummer, Kontakt und \u00d6ffnungszeiten\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auslaenderbehoerde.org\/nl\/immigratiedienst-luckenwalde\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ausl\u00e4nderbeh\u00f6rde Luckenwalde | Adresse und Kontaktdaten\" \/>\n<meta property=\"og:description\" content=\"Ausl\u00e4nderbeh\u00f6rde Luckenwalde | Hier finden Sie alle Informationen wie Adresse und Anschrift \u2713 Telefonnummer, Kontakt und \u00d6ffnungszeiten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auslaenderbehoerde.org\/nl\/immigratiedienst-luckenwalde\/\" \/>\n<meta property=\"og:site_name\" content=\"auslaenderbehoerde.org\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auslaenderbehoerde.org\/wp-content\/uploads\/2022\/06\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/auslaenderbehoerde-luckenwalde\\\/\",\"url\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/auslaenderbehoerde-luckenwalde\\\/\",\"name\":\"Ausl\u00e4nderbeh\u00f6rde Luckenwalde | Adresse und Kontaktdaten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/auslaenderbehoerde-luckenwalde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/auslaenderbehoerde-luckenwalde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg\",\"datePublished\":\"2022-07-11T09:49:26+00:00\",\"description\":\"Ausl\u00e4nderbeh\u00f6rde Luckenwalde | Hier finden Sie alle Informationen wie Adresse und Anschrift \u2713 Telefonnummer, Kontakt und \u00d6ffnungszeiten\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/auslaenderbehoerde-luckenwalde\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auslaenderbehoerde.org\\\/auslaenderbehoerde-luckenwalde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/auslaenderbehoerde-luckenwalde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg\",\"contentUrl\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg\",\"width\":900,\"height\":675,\"caption\":\"Ausl\u00e4nderbeh\u00f6rde\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/auslaenderbehoerde-luckenwalde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ausl\u00e4nderbeh\u00f6rde Luckenwalde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/#website\",\"url\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/\",\"name\":\"auslaenderbehoerde.org\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auslaenderbehoerde.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dienst Vreemdelingenzaken Luckenwalde | adres en contactgegevens","description":"Vreemdelingendienst Luckenwalde | Hier vindt u alle informatie zoals adres en adres \u2713 telefoonnummer, contact en openingstijden","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auslaenderbehoerde.org\/nl\/immigratiedienst-luckenwalde\/","og_locale":"nl_NL","og_type":"article","og_title":"Ausl\u00e4nderbeh\u00f6rde Luckenwalde | Adresse und Kontaktdaten","og_description":"Ausl\u00e4nderbeh\u00f6rde Luckenwalde | Hier finden Sie alle Informationen wie Adresse und Anschrift \u2713 Telefonnummer, Kontakt und \u00d6ffnungszeiten","og_url":"https:\/\/auslaenderbehoerde.org\/nl\/immigratiedienst-luckenwalde\/","og_site_name":"auslaenderbehoerde.org","og_image":[{"width":900,"height":675,"url":"https:\/\/auslaenderbehoerde.org\/wp-content\/uploads\/2022\/06\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-luckenwalde\/","url":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-luckenwalde\/","name":"Dienst Vreemdelingenzaken Luckenwalde | adres en contactgegevens","isPartOf":{"@id":"https:\/\/auslaenderbehoerde.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-luckenwalde\/#primaryimage"},"image":{"@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-luckenwalde\/#primaryimage"},"thumbnailUrl":"https:\/\/auslaenderbehoerde.org\/wp-content\/uploads\/2022\/06\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg","datePublished":"2022-07-11T09:49:26+00:00","description":"Vreemdelingendienst Luckenwalde | Hier vindt u alle informatie zoals adres en adres \u2713 telefoonnummer, contact en openingstijden","breadcrumb":{"@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-luckenwalde\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-luckenwalde\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-luckenwalde\/#primaryimage","url":"https:\/\/auslaenderbehoerde.org\/wp-content\/uploads\/2022\/06\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg","contentUrl":"https:\/\/auslaenderbehoerde.org\/wp-content\/uploads\/2022\/06\/Ausla\u0308nderbeho\u0308rde-scaled-e1656327377843.jpeg","width":900,"height":675,"caption":"Ausl\u00e4nderbeh\u00f6rde"},{"@type":"BreadcrumbList","@id":"https:\/\/auslaenderbehoerde.org\/auslaenderbehoerde-luckenwalde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/auslaenderbehoerde.org\/"},{"@type":"ListItem","position":2,"name":"Ausl\u00e4nderbeh\u00f6rde Luckenwalde"}]},{"@type":"WebSite","@id":"https:\/\/auslaenderbehoerde.org\/#website","url":"https:\/\/auslaenderbehoerde.org\/","name":"auslaenderbehoerde.org","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auslaenderbehoerde.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/pages\/914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/comments?post=914"}],"version-history":[{"count":1,"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/pages\/914\/revisions"}],"predecessor-version":[{"id":915,"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/pages\/914\/revisions\/915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/media\/65"}],"wp:attachment":[{"href":"https:\/\/auslaenderbehoerde.org\/nl\/wp-json\/wp\/v2\/media?parent=914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}